{"id":168,"count":3,"description":"","link":"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/","name":"Distress Oxide Sprays","slug":"distress-oxide-sprays","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Distress Oxide Sprays Archives - Joggles Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Distress Oxide Sprays Archives - Joggles Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/\" \/>\n<meta property=\"og:site_name\" content=\"Joggles Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/\",\"url\":\"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/\",\"name\":\"Distress Oxide Sprays Archives - Joggles Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.joggles.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.joggles.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Distress Oxide Sprays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.joggles.com\/blog\/#website\",\"url\":\"https:\/\/www.joggles.com\/blog\/\",\"name\":\"Joggles Blog\",\"description\":\"Mixed Media, Art Journaling, and Rubber Stamping Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.joggles.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Distress Oxide Sprays Archives - Joggles Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/","og_locale":"en_US","og_type":"article","og_title":"Distress Oxide Sprays Archives - Joggles Blog","og_url":"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/","og_site_name":"Joggles Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/","url":"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/","name":"Distress Oxide Sprays Archives - Joggles Blog","isPartOf":{"@id":"https:\/\/www.joggles.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.joggles.com\/blog\/tag\/distress-oxide-sprays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joggles.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Distress Oxide Sprays"}]},{"@type":"WebSite","@id":"https:\/\/www.joggles.com\/blog\/#website","url":"https:\/\/www.joggles.com\/blog\/","name":"Joggles Blog","description":"Mixed Media, Art Journaling, and Rubber Stamping Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joggles.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.joggles.com\/blog\/wp-json\/wp\/v2\/tags\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joggles.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.joggles.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.joggles.com\/blog\/wp-json\/wp\/v2\/posts?tags=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}